{"id":41337,"date":"2022-11-21T19:30:24","date_gmt":"2022-11-21T19:30:24","guid":{"rendered":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/las-diferencias-entre-la-mesa-de-ayuda-de-ti-y-la-mesa-de-servicio-copy\/"},"modified":"2023-06-07T17:33:05","modified_gmt":"2023-06-07T17:33:05","slug":"la-importancia-de-la-marca","status":"publish","type":"post","link":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/","title":{"rendered":"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa?"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; z_index=&#8221;0&#8243;][vc_column][vc_single_image image=&#8221;42495&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row el_id=&#8221;row-content-page&#8221; css=&#8221;.vc_custom_1674585036169{margin-top: -6% !important;margin-bottom: 0px !important;padding-top: 32px !important;padding-right: 16px !important;padding-bottom: 32px !important;padding-left: 16px !important;background-color: #ffffff !important;}&#8221; z_index=&#8221;1&#8243;][vc_column][vc_row_inner el_id=&#8221;row-header-post-etiqueta&#8221; el_class=&#8221;header-post-etiqueta&#8221;][vc_column_inner][vc_column_text]<div class=\"blog-post-top-bss\"> \r\n\r\n\t\t\t\t\t\t<div class=\"entry-content post-content\"> \r\n\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"post-meta date-color\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"entry-meta single-post-meta clearfix gem-post-date\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"post-meta-right\">\r\n\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-meta-likes\"><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-41337\" title=\"Like this\"><span class=\"zilla-likes-count\">16<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/span> \r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"post-meta-left\" style=\"display: flex;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-meta-author div-display-none-bss\">Por Pamela Iturrieta<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sep div-display-none-bss\"><\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"post-meta-date fecha-1-bss\">  \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext-wrap position--left vertical--center\" style=\" \"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext-icon\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-icon gem-simple-icon gem-icon-pack-material gem-icon-size-custom\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-icon-inner\" style=\"font-size: 16px;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\uf1cc<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\uf1cc<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext__title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-customize title-default\" style=\"\"><span>noviembre 21, 2022<\/span><\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t  \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"sep \"><\/span> \t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext-wrap position--left vertical--center\" style=\" \"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext-icon\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-icon gem-simple-icon gem-icon-pack-material gem-icon-size-custom\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-icon-inner\" style=\"font-size: 16px;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\uf547<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\uf547<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"gem-infotext__title\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-customize title-default\" style=\"\"><span><span class=\"post-meta-categories \"><a href=\"https:\/\/web.valuesite.cl\/index.php\/category\/articulo\/\" title=\"Ver todos los art\u00edculos en Art\u00edculo\">Art\u00edculo<\/a> <span class=\"sep\"><\/span> <a href=\"https:\/\/web.valuesite.cl\/index.php\/category\/valuesite\/\" title=\"Ver todos los art\u00edculos en Valuesite\">Valuesite<\/a><\/span><\/span><\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n \r\n\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t \r\n \r\n\t\t\t\t\t\t<\/div>\r\n \r\n<\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;content-articulo-bss&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h5><span class=\"light\" style=\"color: #000000;\">21 de Noviembre del 2022 <strong>La importancia del branding en tu empresa<\/strong><\/span><\/h5>\n<p>[\/vc_column_text][vc_column_text]Normalmente, si tuvi\u00e9semos que definir el significado de palabra <strong><u>branding<\/u><\/strong> lo relacionar\u00edamos directamente con un concepto, un nombre, un producto, un logotipo o una serie de elementos gr\u00e1ficos que simplemente buscan dar identidad visual a una entidad comercial. Si nos vamos al diccionario de la Real Academia Espa\u00f1ola, la palabra marca se define como \u201cSe\u00f1al que se hace o se pone en alguien o algo, para distinguirlos, o para denotar calidad o pertenencia.\u201d Actualmente el concepto marca es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas que hoy en d\u00eda buscan m\u00e1s que solo vender productos, hoy en d\u00eda lo que se venden son prop\u00f3sitos o historias que busquen establecer v\u00ednculos que van m\u00e1s all\u00e1 de los objetivos comerciales de las empresas.<\/p>\n<p>El principal art\u00edfice de este cambio de paradigma es justamente el <strong>Branding<\/strong>, o tambi\u00e9n conocido como gesti\u00f3n de marca, el cual surge en la d\u00e9cada de los 90\u00b4s con el objetivo de hacer frente a las nuevas necesidades de los consumidores, llevando a las empresas a invertir grandes sumas de dinero en publicidad para cambiar su ideolog\u00eda de comunicaci\u00f3n, pasando de vender sus productos, a vender la marca y sus valores. Hoy en d\u00eda, dicho concepto ha evolucionado y va m\u00e1s all\u00e1 de simplemente comunicar determinados valores, hoy en d\u00eda una marca puede significar sentimientos, emociones e inclusive promesas.<\/p>\n<p>Es por eso que el Branding puede jugar un rol fundamental en tu empresa, desde el punto de vista estrat\u00e9gico ya que te permitir\u00e1 a trav\u00e9s de diversas acciones, unificar la marca, el producto y la experiencia, a trav\u00e9s de la construcci\u00f3n de una identidad de marca que transmita el esp\u00edritu de la organizaci\u00f3n y de esta manera, generar lazos que nos ayuden a llegar a la mente y coraz\u00f3n de los consumidores.<\/p>\n<p>A continuaci\u00f3n, te daremos una serie de consejos que te permitir\u00e1n definir una estrategia de branding para tu empresa:<\/p>\n<h6>Investiga:<\/h6>\n<ul>\n<li>Define tu misi\u00f3n, visi\u00f3n y valores.<\/li>\n<li>\u00bfQu\u00e9 te identifica? \u00bfQu\u00e9 identifica a tus principales competidores?<\/li>\n<li>\u00bfPor qu\u00e9 tus clientes deber\u00edan preferirte a ti y no a tu competencia?<\/li>\n<li>Define tus valores centrales<\/li>\n<li>\u00bfQu\u00e9 mensaje deseas transmitir a tu p\u00fablico?<\/li>\n<\/ul>\n<h6>Conoce a tu p\u00fablico objetivo:<\/h6>\n<ul>\n<li>Crea tu Buyer Persona: C\u00e9ntrate en satisfacer un grupo especifico de personas y define sus principales caracter\u00edsticas. Estudia su comportamiento y apunta hacia un segmento que se sienta identificado o involucrado con tu prop\u00f3sito.<\/li>\n<li>Identifica de manera detallada su perfil, crea una propuesta de valor que sea acorde a sus necesidades, de esta manera podr\u00e1s transmitir un mensaje significativo.<\/li>\n<li>Luego de completado los 2 primeros pasos, define tu Brand persona, es decir, define la personalidad y los valores de tu marca.<\/li>\n<\/ul>\n<h6>Establece tus objetivos:<\/h6>\n<ul>\n<li>\u00bfQuieres aumentar el reconocimiento de tu marca?<\/li>\n<li>\u00bfQuieres cambiar la percepci\u00f3n de tu marca?<\/li>\n<li>\u00bfQuieres aumentar la lealtad de tu marca?<\/li>\n<li>\u00bfQuieres conectar de mejor manera con tu p\u00fablico?<\/li>\n<li>\u00bfQuieres renovar la imagen?<\/li>\n<\/ul>\n<p>Recuerda que, en este caso, es fundamental que, al momento de establecer tus objetivos, estos deben ser espec\u00edficos, medibles, alcanzables, relevantes y con l\u00edmite de tiempo. (SMART)<\/p>\n<h6>Define tu promesa de marca:<\/h6>\n<ul>\n<li>Debe ser <strong>relevante<\/strong>, es decir, definir lo que los clientes realmente necesitan o aquello que es relevante para ellos.<\/li>\n<li>Debe ser <strong>coherente,<\/strong> es decir, lo que dices tiene que verse reflejado en lo que haces. Define de qu\u00e9 manera puedes aportar valor y construye tu promesa en funci\u00f3n de eso.<\/li>\n<li>Debe ser \u00bfQu\u00e9 es lo que me define y de qu\u00e9 manera puedo establecer diferencias con mis competidores?<\/li>\n<li>Debe <strong>trascender<\/strong> en el tiempo, recuerda que una promesa es un compromiso que debe ser cumplido siempre con tus clientes.<\/li>\n<\/ul>\n<p>Entonces, \u00bfPor qu\u00e9 es tan importante contar con una estrategia de branding? Debes tener en consideraci\u00f3n que, independiente del grado de competitividad de la industria en la que te encuentres actualmente, siempre es importante diferenciarte de tus competidores y es ah\u00ed, donde contar con una estrategia de branding es fundamental para aumentar el grado de percepci\u00f3n de tu marca y establecer v\u00ednculos que te conecten con tu p\u00fablico objetivo de manera m\u00e1s cercana. Recuerda que ser \u00fanico y tener caracter\u00edsticas que te distingan de los dem\u00e1s es una de las cuantas maneras en la que puedes cautivar y llegar al coraz\u00f3n de tus clientes ya que as\u00ed le dar\u00e1s motivos para preferir a tu empresa por sobre las otras y se sentir\u00e1n privilegiados de parte de lo que tu empresa promueve.<\/p>\n<p>Te invitamos a trabajar junto a nuestro equipo de profesionales con amplia experiencia en el desarrollo de soluciones tecnol\u00f3gicas para diferentes industrias, que agregan valor a nuestros clientes.<\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cont\u00e1ctanos a trav\u00e9s de nuestro correo\u00a0<\/span><\/span><\/span><\/span><a href=\"mailto:contacto@valuesite.cl\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">contacto@valuesite.cl<\/span><\/span><\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00a0y s\u00edguenos en nuestras redes sociales en\u00a0<\/span><\/span><\/span><\/span><a href=\"https:\/\/www.instagram.com\/valuesitechile\/?hl=es\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Instagram<\/span><\/span><\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">,\u00a0<\/span><\/span><\/span><\/span><a href=\"https:\/\/www.facebook.com\/valuesitechile\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Facebook<\/span><\/span><\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">,\u00a0<\/span><\/span><\/span><\/span><a href=\"https:\/\/twitter.com\/valuesitechile\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Twitter<\/span><\/span><\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00a0y\u00a0<\/span><\/span><\/span><\/span><a href=\"https:\/\/www.linkedin.com\/company\/valuesitechile\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">LinkedIn<\/span><\/span><\/span><\/span><\/a><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">.<\/span><\/span><\/span><\/span><\/p>\n<h5 style=\"text-align: center;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00a1TE ESPERAMOS!<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/h5>\n<div class=\"small-body\"><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;row-footer-post-etiqueta&#8221; el_class=&#8221;footer-post-etiqueta&#8221;][vc_column_inner][vc_column_text]<!-- CATEGORIA-BSS -->\r\n<div class=\"row-etiqueta-post-bss\">\r\n\t\t\t\t\t<div class=\"post-tags-list date-color\"><a href=\"https:\/\/web.valuesite.cl\/index.php\/tag\/digitalizacion\/\" rel=\"tag\">Digitalizaci\u00f3n<\/a><a href=\"https:\/\/web.valuesite.cl\/index.php\/tag\/marketing-digital\/\" rel=\"tag\">Marketing digital<\/a><\/div><!-- .CATEGORIA-BSS --> [\/vc_column_text]<div class=\"thegem-template-wrapper thegem-template-content thegem-template-41932\"><style>.vc_custom_1676988735466{margin-top: 32px !important;}.div-content-redessolciales .wpb_wrapper{    display: flex;    flex-direction: row;    align-content: center;    justify-content: center;    gap: 32px;    align-items: baseline;}.wpb_text_column ul li:before {    left:0px;    content: &quot;&quot;;    height: 0px;    width: 0px;    position: absolute;    background-color: #002b36;    border-radius: 50%;    top: 0px;    display:none;}@media (max-width: 500px) {.div-content-redessolciales .wpb_wrapper {    display: flex;    flex-direction: column;    justify-content: center;    gap: 8px;    align-items: center;    align-content: center;    flex-wrap: wrap;}  }<\/style><p><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span>[vc_row equal_height=\"yes\" content_placement=\"middle\" el_class=\"div-content-redessolciales\" el_id=\"row-div-content-redessolciales\" css=\".vc_custom_1676988735466{margin-top: 32px !important;}\"][vc_column el_class=\"div-content-redessolciales\"][vc_column_text]<\/p>\r\n<p class=\"text-redessociales\">\u00a1Comparte este art\u00edculo!<\/p>\r\n<p>[\/vc_column_text]<style>.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing ul {margin-left: -0px; margin-right: -0px;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing ul li {padding-left: 0px; padding-right: 0px;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing ul li {margin-top: 0px; margin-bottom: 0px;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item-icon {font-size: 16px;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item {min-width: 22px;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item {min-height: 22px;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item {color: #ffffff;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item {background-color: #9a9a9a;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item:hover {background-color: #f7f7f7;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item {border-color: #ffffff;}.thegem-te-socials-sharing.thegem-custom-6a581cbe82bc17438 .socials-sharing .socials-item:hover {border-color: #ffffff;}<\/style><div class=\"thegem-te-socials-sharing socials-sharing--left socials-sharing--round socials-sharing--custom thegem-custom-6a581cbe82bc17438\"> <div class=\"socials-sharing\"> <ul> <li><a class=\"socials-item facebook\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fweb.valuesite.cl%2Findex.php%2F2022%2F11%2F21%2Fla-importancia-de-la-marca%2F\" title=\"Facebook\"><i class=\"socials-item-icon facebook\"><\/i><\/a><\/li> <li><a class=\"socials-item twitter\" target=\"_blank\" href=\"https:\/\/twitter.com\/intent\/tweet?text=%C2%BFQu%C3%A9+es+branding%3F+y+%C2%BFPor+qu%C3%A9+es+tan+importante+para+tu+empresa%3F&#038;url=https%3A%2F%2Fweb.valuesite.cl%2Findex.php%2F2022%2F11%2F21%2Fla-importancia-de-la-marca%2F\" title=\"Twitter\"><i class=\"socials-item-icon twitter\"><\/i><\/a><\/li> <li><a class=\"socials-item linkedin\" target=\"_blank\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fweb.valuesite.cl%2Findex.php%2F2022%2F11%2F21%2Fla-importancia-de-la-marca%2F&#038;title=%C2%BFQu%C3%A9+es+branding%3F+y+%C2%BFPor+qu%C3%A9+es+tan+importante+para+tu+empresa%3F&amp;summary=Actualmente+el+concepto+branding+es+mucho+m%C3%A1s+complejo+que+eso%2C+y+esto+se+debe+principalmente+a+la+evoluci%C3%B3n+constante+de+las+empresas+que+hoy+en+d%C3%ADa+buscan+m%C3%A1s+que+solo+vender+productos%2C+hoy+en+d%C3%ADa+lo+que+se+venden+son+prop%C3%B3sitos+o+historias+que+busquen+establecer+v%C3%ADnculos+que+van+m%C3%A1s+all%C3%A1+de+los+objetivos+comerciales+de+las+empresas...\" title=\"LinkedIn\"><i class=\"socials-item-icon linkedin\"><\/i><\/a><\/li> <li><a class=\"socials-item whatsapp\" target=\"_blank\" href=\"https:\/\/wa.me\/?text=https%3A%2F%2Fweb.valuesite.cl%2Findex.php%2F2022%2F11%2F21%2Fla-importancia-de-la-marca%2F\" title=\"WhatsApp\"><i class=\"socials-item-icon whatsapp\"><\/i><\/a><\/li> <\/ul> <\/div> <\/div>[\/vc_column][\/vc_row]<span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_end\">\ufeff<\/span>[vc_row el_disable_desktop=\"1\" el_disable_tablet=\"1\" el_disable_mobile=\"1\"][vc_column]<div class=\"socials socials-list socials-colored-hover socials-rounded socials-alignment-left\"><a class=\"socials-item\" target=\"_blank\" href=\"https:\/\/www.linkedin.com\/company\/valuesite\" style=\"color: #9a9a9a;\"><i class=\"socials-item-icon linkedin\" style=\"font-size: 24px\"><\/i><\/a><a class=\"socials-item\" target=\"_blank\" href=\"https:\/\/twitter.com\/valuesitechile\" style=\"color: #9a9a9a;\"><i class=\"socials-item-icon twitter\" style=\"font-size: 24px\"><\/i><\/a><a class=\"socials-item\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/valuesitechile\" style=\"color: #9a9a9a;\"><i class=\"socials-item-icon facebook\" style=\"font-size: 24px\"><\/i><\/a><a class=\"socials-item\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/valuesitechile\" style=\"color: #9a9a9a;\"><i class=\"socials-item-icon instagram\" style=\"font-size: 24px\"><\/i><\/a><a class=\"socials-item\" target=\"_blank\" href=\"https:\/\/youtube.com\/channel\/UCwNWwDg2BgdQH6rOgsgQuOg\" style=\"color: #9a9a9a;\"><i class=\"socials-item-icon youtube\" style=\"font-size: 24px\"><\/i><\/a><\/div>[\/vc_column][\/vc_row]<\/p>\r\n<\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas que hoy en d\u00eda buscan m\u00e1s que solo vender productos, hoy en d\u00eda lo que se venden son prop\u00f3sitos o historias que busquen establecer v\u00ednculos que van m\u00e1s all\u00e1 de los objetivos comerciales de las empresas&#8230;<\/p>\n","protected":false},"author":13,"featured_media":42496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[128,125],"tags":[130,155],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa? | Valuesite<\/title>\n<meta name=\"description\" content=\"Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa? | Valuesite\" \/>\n<meta property=\"og:description\" content=\"Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\" \/>\n<meta property=\"og:site_name\" content=\"Valuesite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valuesitechile\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T19:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T17:33:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.valuesite.cl\/wp-content\/uploads\/2022\/11\/Imagen-destacada-importancia-del-branding.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pamela Iturrieta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@valuesitechile\" \/>\n<meta name=\"twitter:site\" content=\"@valuesitechile\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pamela Iturrieta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\"},\"author\":{\"name\":\"Pamela Iturrieta\",\"@id\":\"https:\/\/web.valuesite.cl\/#\/schema\/person\/d5718faa254837cca112a30886eeea7d\"},\"headline\":\"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa?\",\"datePublished\":\"2022-11-21T19:30:24+00:00\",\"dateModified\":\"2023-06-07T17:33:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\"},\"wordCount\":1013,\"publisher\":{\"@id\":\"https:\/\/web.valuesite.cl\/#organization\"},\"keywords\":[\"Digitalizaci\u00f3n\",\"Marketing digital\"],\"articleSection\":[\"Art\u00edculo\",\"Valuesite\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\",\"url\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\",\"name\":\"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa? | Valuesite\",\"isPartOf\":{\"@id\":\"https:\/\/web.valuesite.cl\/#website\"},\"datePublished\":\"2022-11-21T19:30:24+00:00\",\"dateModified\":\"2023-06-07T17:33:05+00:00\",\"description\":\"Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas.\",\"breadcrumb\":{\"@id\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/web.valuesite.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/web.valuesite.cl\/#website\",\"url\":\"https:\/\/web.valuesite.cl\/\",\"name\":\"Valuesite\",\"description\":\"\u00a1Soluciones de valor para tu empresa!\",\"publisher\":{\"@id\":\"https:\/\/web.valuesite.cl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/web.valuesite.cl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/web.valuesite.cl\/#organization\",\"name\":\"Valuesite\",\"url\":\"https:\/\/web.valuesite.cl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/web.valuesite.cl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/web.valuesite.cl\/wp-content\/uploads\/2022\/12\/Logo_valuesite_color.png\",\"contentUrl\":\"https:\/\/web.valuesite.cl\/wp-content\/uploads\/2022\/12\/Logo_valuesite_color.png\",\"width\":817,\"height\":144,\"caption\":\"Valuesite\"},\"image\":{\"@id\":\"https:\/\/web.valuesite.cl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/valuesitechile\",\"https:\/\/twitter.com\/valuesitechile\",\"https:\/\/www.instagram.com\/valuesitechile\",\"https:\/\/www.linkedin.com\/company\/valuesite\",\"https:\/\/youtube.com\/channel\/UCwNWwDg2BgdQH6rOgsgQuOg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/web.valuesite.cl\/#\/schema\/person\/d5718faa254837cca112a30886eeea7d\",\"name\":\"Pamela Iturrieta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/web.valuesite.cl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a42c07c44e499b7024d4e82064a3f12?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a42c07c44e499b7024d4e82064a3f12?s=96&d=mm&r=g\",\"caption\":\"Pamela Iturrieta\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa? | Valuesite","description":"Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa? | Valuesite","og_description":"Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas.","og_url":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/","og_site_name":"Valuesite","article_publisher":"https:\/\/www.facebook.com\/valuesitechile","article_published_time":"2022-11-21T19:30:24+00:00","article_modified_time":"2023-06-07T17:33:05+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/web.valuesite.cl\/wp-content\/uploads\/2022\/11\/Imagen-destacada-importancia-del-branding.jpg","type":"image\/jpeg"}],"author":"Pamela Iturrieta","twitter_card":"summary_large_image","twitter_creator":"@valuesitechile","twitter_site":"@valuesitechile","twitter_misc":{"Escrito por":"Pamela Iturrieta","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/#article","isPartOf":{"@id":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/"},"author":{"name":"Pamela Iturrieta","@id":"https:\/\/web.valuesite.cl\/#\/schema\/person\/d5718faa254837cca112a30886eeea7d"},"headline":"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa?","datePublished":"2022-11-21T19:30:24+00:00","dateModified":"2023-06-07T17:33:05+00:00","mainEntityOfPage":{"@id":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/"},"wordCount":1013,"publisher":{"@id":"https:\/\/web.valuesite.cl\/#organization"},"keywords":["Digitalizaci\u00f3n","Marketing digital"],"articleSection":["Art\u00edculo","Valuesite"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/","url":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/","name":"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa? | Valuesite","isPartOf":{"@id":"https:\/\/web.valuesite.cl\/#website"},"datePublished":"2022-11-21T19:30:24+00:00","dateModified":"2023-06-07T17:33:05+00:00","description":"Actualmente el concepto branding es mucho m\u00e1s complejo que eso, y esto se debe principalmente a la evoluci\u00f3n constante de las empresas.","breadcrumb":{"@id":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web.valuesite.cl\/index.php\/2022\/11\/21\/la-importancia-de-la-marca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/web.valuesite.cl\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es branding? y \u00bfPor qu\u00e9 es tan importante para tu empresa?"}]},{"@type":"WebSite","@id":"https:\/\/web.valuesite.cl\/#website","url":"https:\/\/web.valuesite.cl\/","name":"Valuesite","description":"\u00a1Soluciones de valor para tu empresa!","publisher":{"@id":"https:\/\/web.valuesite.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.valuesite.cl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/web.valuesite.cl\/#organization","name":"Valuesite","url":"https:\/\/web.valuesite.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/web.valuesite.cl\/#\/schema\/logo\/image\/","url":"https:\/\/web.valuesite.cl\/wp-content\/uploads\/2022\/12\/Logo_valuesite_color.png","contentUrl":"https:\/\/web.valuesite.cl\/wp-content\/uploads\/2022\/12\/Logo_valuesite_color.png","width":817,"height":144,"caption":"Valuesite"},"image":{"@id":"https:\/\/web.valuesite.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valuesitechile","https:\/\/twitter.com\/valuesitechile","https:\/\/www.instagram.com\/valuesitechile","https:\/\/www.linkedin.com\/company\/valuesite","https:\/\/youtube.com\/channel\/UCwNWwDg2BgdQH6rOgsgQuOg"]},{"@type":"Person","@id":"https:\/\/web.valuesite.cl\/#\/schema\/person\/d5718faa254837cca112a30886eeea7d","name":"Pamela Iturrieta","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/web.valuesite.cl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a42c07c44e499b7024d4e82064a3f12?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a42c07c44e499b7024d4e82064a3f12?s=96&d=mm&r=g","caption":"Pamela Iturrieta"}}]}},"menu_order":0,"_links":{"self":[{"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/posts\/41337"}],"collection":[{"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/comments?post=41337"}],"version-history":[{"count":14,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/posts\/41337\/revisions"}],"predecessor-version":[{"id":42510,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/posts\/41337\/revisions\/42510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/media\/42496"}],"wp:attachment":[{"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/media?parent=41337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/categories?post=41337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.valuesite.cl\/index.php\/wp-json\/wp\/v2\/tags?post=41337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}